{"id":34996,"date":"2014-07-19T16:45:27","date_gmt":"2014-07-19T14:45:27","guid":{"rendered":"http:\/\/www.voismagazine.it\/dp\/?p=34996"},"modified":"2014-11-22T18:17:56","modified_gmt":"2014-11-22T17:17:56","slug":"feditalimprese-nuova-sede-ad-adrano-ct","status":"publish","type":"post","link":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/","title":{"rendered":"Feditalimprese: nuova sede ad Adrano ( CT )"},"content":{"rendered":"<div id=\"voism-2427035609\" class=\"voism-prima-del-contenuto voism-entity-placement\"><a href=\"https:\/\/amzn.to\/2Y0db7E\" aria-label=\"\"><\/a><\/div><p dir=\"ltr\" style=\"text-align: justify;\"><a href=\"http:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/image-303\/\" rel=\"attachment wp-att-34999\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-34999\" src=\"http:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2014\/07\/image1-225x300.jpg\" alt=\"image\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2014\/07\/image1-225x300.jpg 225w, https:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2014\/07\/image1-768x1024.jpg 768w, https:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2014\/07\/image1.jpg 960w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><span style=\"font-size: small;\"><span style=\"background-color: rgba(255, 255, 255, 0);\">Oggi 19 Luglio 2014, in via Cavour n. 10 ad Adrano, sar\u00e0 inaugurata la nuova sede locale di Feditalimprese Sicilia. Alla cerimonia saranno presenti il Sindaco di Adrano,\u00a0 Pippo Ferrante, il presidente della Confederazione Nazionale Feditalimprese Gianluca Micalizzi, il vice-presidente di Feditalimprese Sicilia Antonino Neri, il Direttore Regionale di Feditalimprese Sicilia Giuseppe Torrisi, il presidente di Feditalimprese Donna Impresa Rosita Cantale, il presidente della Federazione Armatori Carmelo Micalizzi, oltre naturalmente al neo segretario comunale di Feditalimprese Adrano Agata Salines. Tra i presenti anche lo scrittore Agostino Portanova e rappresentanti istituzionali e dell&#8217;imprenditoria locale.<\/span><\/span><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><span style=\"font-size: small;\"><span style=\"background-color: rgba(255, 255, 255, 0);\">&lt;&lt;Finalmente anche ad Adrano apriamo una sede di Feditalimprese, afferma il presidente della Confederazione Nazionale Feditalimprese, Gianluca Micalizzi- in meno di quattro anni abbiamo creato una struttura importante\u00a0 per venire incontro alle esigenze degli imprenditori. Adrano \u00e8 una piazza importante per il tessuto imprenditoriale,\u00a0 ed in questo particolare momento di crisi economica \u00e8 fondamentale affiancare le piccole e medie imprese sostenendo le loro attivit\u00e0 e offrendo assistenza e servizi a 360*. Siamo particolarmente felici \u2013 ha concluso Micalizzi- perch\u00e9 gli imprenditori ci danno fiducia e contribuiscono alla crescita dell\u2019organizzazione&gt;&gt;.<\/span><\/span><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><span style=\"font-size: small;\"><span style=\"background-color: rgba(255, 255, 255, 0);\">Feditalimprese a meno di quattro anni dalla fondazione, conta circa venti sedi in Sicilia,\u00a0 e da quest&#8217;anno ha iniziato la radicalizzazione in tutto in territorio nazionale con aperture in Puglia, Piemonte e Campania, Attraverso le sue sedi Feditalimprese vuole essere un punto di riferimento per imprese ed imprenditori, dando l&#8217;opportunit\u00e0 di avere una sede in ogni comune.<\/span><\/span><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><span style=\"font-size: small;\"><span style=\"background-color: rgba(255, 255, 255, 0);\">Ad Adrano , cos\u00ec come avviene nelle altre sedi , verranno forniti servizi di consulenza (legale, contabile, assicurativa, formativa, etc ) corsi di formazione, aiuti per l\u2019accesso ai finanziamenti, caf e Patronato. La parola d\u2019ordine sar\u00e0 quindi facilitazione delle procedure burocratiche, troppo spesso ostacolo per chi ha voglia di mettersi in gioco e aprire una nuova attivit\u00e0.<\/span><\/span><\/p>\n<div id=\"voism-2499499684\" class=\"voism-fine voism-entity-placement\"><a href=\"https:\/\/amzn.to\/2Y0db7E\" aria-label=\"\"><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Oggi 19 Luglio 2014, in via Cavour n. 10 ad Adrano, sar\u00e0 inaugurata la nuova sede locale di Feditalimprese Sicilia. Alla cerimonia saranno presenti il Sindaco di Adrano,\u00a0 Pippo Ferrante, il presidente della Confederazione Nazionale Feditalimprese Gianluca Micalizzi, il vice-presidente di Feditalimprese Sicilia Antonino Neri, il Direttore Regionale di Feditalimprese Sicilia Giuseppe Torrisi, il presidente &#8230;<\/p>\n","protected":false},"author":14,"featured_media":34999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1740,6678,2454],"tags":[],"class_list":["post-34996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-incopertina","category-mondo-imprese","category-news"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Oggi 19 Luglio 2014, in via Cavour n. 10 ad Adrano, sar\u00e0 inaugurata la nuova sede locale di Feditalimprese Sicilia. Alla cerimonia saranno presenti il Sindaco di Adrano, Pippo Ferrante, il presidente della Confederazione Nazionale Feditalimprese Gianluca Micalizzi, il vice-presidente di Feditalimprese Sicilia Antonino Neri, il Direttore Regionale di Feditalimprese Sicilia Giuseppe Torrisi, il presidente\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Gianluca Micalizzi\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"VOIS MAGAZINE | Notizie | Curiosit\u00e0 | Eventi | Gossip |Imprese\" \/>\n\t\t<meta property=\"og:type\" content=\"activity\" \/>\n\t\t<meta property=\"og:title\" content=\"Feditalimprese: nuova sede ad Adrano ( CT ) | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |\" \/>\n\t\t<meta property=\"og:description\" content=\"Oggi 19 Luglio 2014, in via Cavour n. 10 ad Adrano, sar\u00e0 inaugurata la nuova sede locale di Feditalimprese Sicilia. Alla cerimonia saranno presenti il Sindaco di Adrano, Pippo Ferrante, il presidente della Confederazione Nazionale Feditalimprese Gianluca Micalizzi, il vice-presidente di Feditalimprese Sicilia Antonino Neri, il Direttore Regionale di Feditalimprese Sicilia Giuseppe Torrisi, il presidente\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2014\/07\/image1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2014\/07\/image1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Feditalimprese: nuova sede ad Adrano ( CT ) | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Oggi 19 Luglio 2014, in via Cavour n. 10 ad Adrano, sar\u00e0 inaugurata la nuova sede locale di Feditalimprese Sicilia. Alla cerimonia saranno presenti il Sindaco di Adrano, Pippo Ferrante, il presidente della Confederazione Nazionale Feditalimprese Gianluca Micalizzi, il vice-presidente di Feditalimprese Sicilia Antonino Neri, il Direttore Regionale di Feditalimprese Sicilia Giuseppe Torrisi, il presidente\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2014\/07\/image1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2014\\\/07\\\/19\\\/feditalimprese-nuova-sede-ad-adrano-ct\\\/#article\",\"name\":\"Feditalimprese: nuova sede ad Adrano ( CT ) | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\\u00c3 | Eventi | Politica |\",\"headline\":\"Feditalimprese: nuova sede ad Adrano ( CT )\",\"author\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/author\\\/gianluca-micalizzi\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/image1.jpg\",\"width\":960,\"height\":1280},\"datePublished\":\"2014-07-19T16:45:27+02:00\",\"dateModified\":\"2014-11-22T18:17:56+01:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2014\\\/07\\\/19\\\/feditalimprese-nuova-sede-ad-adrano-ct\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2014\\\/07\\\/19\\\/feditalimprese-nuova-sede-ad-adrano-ct\\\/#webpage\"},\"articleSection\":\"inCopertina, Mondo Imprese, News\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2014\\\/07\\\/19\\\/feditalimprese-nuova-sede-ad-adrano-ct\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/#listItem\",\"name\":\"Informazione\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/#listItem\",\"position\":2,\"name\":\"Informazione\",\"item\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/news\\\/#listItem\",\"name\":\"News\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/news\\\/#listItem\",\"position\":3,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2014\\\/07\\\/19\\\/feditalimprese-nuova-sede-ad-adrano-ct\\\/#listItem\",\"name\":\"Feditalimprese: nuova sede ad Adrano ( CT )\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/#listItem\",\"name\":\"Informazione\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2014\\\/07\\\/19\\\/feditalimprese-nuova-sede-ad-adrano-ct\\\/#listItem\",\"position\":4,\"name\":\"Feditalimprese: nuova sede ad Adrano ( CT )\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/news\\\/#listItem\",\"name\":\"News\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/#organization\",\"name\":\"VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\\u00c3  | Eventi | Politica |\",\"url\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/author\\\/gianluca-micalizzi\\\/#author\",\"url\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/author\\\/gianluca-micalizzi\\\/\",\"name\":\"Gianluca Micalizzi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2014\\\/07\\\/19\\\/feditalimprese-nuova-sede-ad-adrano-ct\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e645c53110e5fbe4d72191bcae19095638e3d659babaef81e35ab6bc0799945e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Gianluca Micalizzi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2014\\\/07\\\/19\\\/feditalimprese-nuova-sede-ad-adrano-ct\\\/#webpage\",\"url\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2014\\\/07\\\/19\\\/feditalimprese-nuova-sede-ad-adrano-ct\\\/\",\"name\":\"Feditalimprese: nuova sede ad Adrano ( CT ) | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\\u00c3 | Eventi | Politica |\",\"description\":\"Oggi 19 Luglio 2014, in via Cavour n. 10 ad Adrano, sar\\u00e0 inaugurata la nuova sede locale di Feditalimprese Sicilia. Alla cerimonia saranno presenti il Sindaco di Adrano, Pippo Ferrante, il presidente della Confederazione Nazionale Feditalimprese Gianluca Micalizzi, il vice-presidente di Feditalimprese Sicilia Antonino Neri, il Direttore Regionale di Feditalimprese Sicilia Giuseppe Torrisi, il presidente\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2014\\\/07\\\/19\\\/feditalimprese-nuova-sede-ad-adrano-ct\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/author\\\/gianluca-micalizzi\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/author\\\/gianluca-micalizzi\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/image1.jpg\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2014\\\/07\\\/19\\\/feditalimprese-nuova-sede-ad-adrano-ct\\\/#mainImage\",\"width\":960,\"height\":1280},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2014\\\/07\\\/19\\\/feditalimprese-nuova-sede-ad-adrano-ct\\\/#mainImage\"},\"datePublished\":\"2014-07-19T16:45:27+02:00\",\"dateModified\":\"2014-11-22T18:17:56+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/#website\",\"url\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/\",\"name\":\"VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\\u00c3  | Eventi | Politica |\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Feditalimprese: nuova sede ad Adrano ( CT ) | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |","description":"Oggi 19 Luglio 2014, in via Cavour n. 10 ad Adrano, sar\u00e0 inaugurata la nuova sede locale di Feditalimprese Sicilia. Alla cerimonia saranno presenti il Sindaco di Adrano, Pippo Ferrante, il presidente della Confederazione Nazionale Feditalimprese Gianluca Micalizzi, il vice-presidente di Feditalimprese Sicilia Antonino Neri, il Direttore Regionale di Feditalimprese Sicilia Giuseppe Torrisi, il presidente","canonical_url":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/#article","name":"Feditalimprese: nuova sede ad Adrano ( CT ) | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |","headline":"Feditalimprese: nuova sede ad Adrano ( CT )","author":{"@id":"https:\/\/www.voismagazine.it\/dp\/author\/gianluca-micalizzi\/#author"},"publisher":{"@id":"https:\/\/www.voismagazine.it\/dp\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2014\/07\/image1.jpg","width":960,"height":1280},"datePublished":"2014-07-19T16:45:27+02:00","dateModified":"2014-11-22T18:17:56+01:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/#webpage"},"isPartOf":{"@id":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/#webpage"},"articleSection":"inCopertina, Mondo Imprese, News"},{"@type":"BreadcrumbList","@id":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp#listItem","position":1,"name":"Home","item":"https:\/\/www.voismagazine.it\/dp","nextItem":{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/#listItem","name":"Informazione"}},{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/#listItem","position":2,"name":"Informazione","item":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/news\/#listItem","name":"News"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/news\/#listItem","position":3,"name":"News","item":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/#listItem","name":"Feditalimprese: nuova sede ad Adrano ( CT )"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/#listItem","name":"Informazione"}},{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/#listItem","position":4,"name":"Feditalimprese: nuova sede ad Adrano ( CT )","previousItem":{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/news\/#listItem","name":"News"}}]},{"@type":"Organization","@id":"https:\/\/www.voismagazine.it\/dp\/#organization","name":"VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3  | Eventi | Politica |","url":"https:\/\/www.voismagazine.it\/dp\/"},{"@type":"Person","@id":"https:\/\/www.voismagazine.it\/dp\/author\/gianluca-micalizzi\/#author","url":"https:\/\/www.voismagazine.it\/dp\/author\/gianluca-micalizzi\/","name":"Gianluca Micalizzi","image":{"@type":"ImageObject","@id":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e645c53110e5fbe4d72191bcae19095638e3d659babaef81e35ab6bc0799945e?s=96&d=mm&r=g","width":96,"height":96,"caption":"Gianluca Micalizzi"}},{"@type":"WebPage","@id":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/#webpage","url":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/","name":"Feditalimprese: nuova sede ad Adrano ( CT ) | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |","description":"Oggi 19 Luglio 2014, in via Cavour n. 10 ad Adrano, sar\u00e0 inaugurata la nuova sede locale di Feditalimprese Sicilia. Alla cerimonia saranno presenti il Sindaco di Adrano, Pippo Ferrante, il presidente della Confederazione Nazionale Feditalimprese Gianluca Micalizzi, il vice-presidente di Feditalimprese Sicilia Antonino Neri, il Direttore Regionale di Feditalimprese Sicilia Giuseppe Torrisi, il presidente","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.voismagazine.it\/dp\/#website"},"breadcrumb":{"@id":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/#breadcrumblist"},"author":{"@id":"https:\/\/www.voismagazine.it\/dp\/author\/gianluca-micalizzi\/#author"},"creator":{"@id":"https:\/\/www.voismagazine.it\/dp\/author\/gianluca-micalizzi\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2014\/07\/image1.jpg","@id":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/#mainImage","width":960,"height":1280},"primaryImageOfPage":{"@id":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/#mainImage"},"datePublished":"2014-07-19T16:45:27+02:00","dateModified":"2014-11-22T18:17:56+01:00"},{"@type":"WebSite","@id":"https:\/\/www.voismagazine.it\/dp\/#website","url":"https:\/\/www.voismagazine.it\/dp\/","name":"VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3  | Eventi | Politica |","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.voismagazine.it\/dp\/#organization"}}]},"og:locale":"it_IT","og:site_name":"VOIS MAGAZINE | Notizie | Curiosit\u00e0 | Eventi | Gossip |Imprese","og:type":"activity","og:title":"Feditalimprese: nuova sede ad Adrano ( CT ) | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |","og:description":"Oggi 19 Luglio 2014, in via Cavour n. 10 ad Adrano, sar\u00e0 inaugurata la nuova sede locale di Feditalimprese Sicilia. Alla cerimonia saranno presenti il Sindaco di Adrano, Pippo Ferrante, il presidente della Confederazione Nazionale Feditalimprese Gianluca Micalizzi, il vice-presidente di Feditalimprese Sicilia Antonino Neri, il Direttore Regionale di Feditalimprese Sicilia Giuseppe Torrisi, il presidente","og:url":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/","og:image":"https:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2014\/07\/image1.jpg","og:image:secure_url":"https:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2014\/07\/image1.jpg","og:image:width":960,"og:image:height":1280,"twitter:card":"summary","twitter:title":"Feditalimprese: nuova sede ad Adrano ( CT ) | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |","twitter:description":"Oggi 19 Luglio 2014, in via Cavour n. 10 ad Adrano, sar\u00e0 inaugurata la nuova sede locale di Feditalimprese Sicilia. Alla cerimonia saranno presenti il Sindaco di Adrano, Pippo Ferrante, il presidente della Confederazione Nazionale Feditalimprese Gianluca Micalizzi, il vice-presidente di Feditalimprese Sicilia Antonino Neri, il Direttore Regionale di Feditalimprese Sicilia Giuseppe Torrisi, il presidente","twitter:image":"https:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2014\/07\/image1.jpg"},"aioseo_meta_data":{"post_id":"34996","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"activity","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-12-28 10:42:34","updated":"2025-12-28 10:42:34","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.voismagazine.it\/dp\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/\" title=\"Informazione\">Informazione<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/news\/\" title=\"News\">News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFeditalimprese: nuova sede ad Adrano ( CT )\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.voismagazine.it\/dp"},{"label":"Informazione","link":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/"},{"label":"News","link":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/news\/"},{"label":"Feditalimprese: nuova sede ad Adrano ( CT )","link":"https:\/\/www.voismagazine.it\/dp\/2014\/07\/19\/feditalimprese-nuova-sede-ad-adrano-ct\/"}],"_links":{"self":[{"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/posts\/34996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/comments?post=34996"}],"version-history":[{"count":5,"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/posts\/34996\/revisions"}],"predecessor-version":[{"id":35971,"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/posts\/34996\/revisions\/35971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/media\/34999"}],"wp:attachment":[{"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/media?parent=34996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/categories?post=34996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/tags?post=34996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}