{"id":1475,"date":"2012-10-25T12:40:39","date_gmt":"2012-10-25T10:40:39","guid":{"rendered":"http:\/\/www.voismagazine.it\/dp\/?p=1475"},"modified":"2012-11-18T15:56:47","modified_gmt":"2012-11-18T14:56:47","slug":"verso-palermo-2050-le-nuove-linee-guida-del-prg","status":"publish","type":"post","link":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/","title":{"rendered":"Verso Palermo 2050, le nuove linee guida del PRG"},"content":{"rendered":"<div id=\"voism-2114807622\" class=\"voism-prima-del-contenuto voism-entity-placement\"><a href=\"https:\/\/amzn.to\/2Y0db7E\" aria-label=\"\"><\/a><\/div><p><strong><a href=\"http:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2012\/10\/image71-e1351161597123.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1480\" title=\"Palermo PGR\" src=\"http:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2012\/10\/image71-e1351161583775-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a>PALERMO: <\/strong>Sono state presentate oggi, nel corso di una conferenza stampa a Villa\u00a0Niscemi, le linee guida elaborate dalla Giunta Comunale per la\u00a0redazione del nuovo Piano Regolatore.<br \/>\nDi seguito una sintesi della presentazione.<br \/>\nIl nuovo Piano Regolatore Generale di Palermo sar\u00e0 lo strumento per\u00a0trasformare la citt\u00e0 rendendola contemporanea, moderna e sostenibile.\u00a0Miriamo a modellare lo sviluppo della Palermo del futuro, del 2050. Si\u00a0tratta ovviamente di un processo tanto complesso quanto ambizioso, di\u00a0cui le linee guida approvate dalla Giunta comunale e appena trasmesse\u00a0al Consiglio Comunale per la discussione e l\u2019approvazione\u00a0costituiscono la cornice entro cui inserire il confronto; tali linee\u00a0guida costituiscono e costituiranno il punto di riferimento di un\u00a0processo che dovr\u00e0 essere concertato e condiviso con tutti gli attori\u00a0della vita sociale della citt\u00e0. Un percorso che vedr\u00e0 la\u00a0partecipazione dei mondi vitali, delle professioni, della ricerca e\u00a0della cultura, cos\u00ec come percorsi di dialogo e partecipazione rivolti\u00a0in modo innovativo al confronto con la scuola, come luogo simbolo del\u00a0legame fra presente e futuro.<\/p>\n<p>Le direttive sono semplici. La sfida del nuovo PRG sar\u00e0, in prima\u00a0istanza, quella di supportare e rendere credibile la candidatura di\u00a0Palermo a Capitale Europea della Cultura nel 2019, confermando il suo\u00a0ruolo di metropoli interculturale del Mediterraneo.\u00a0Il metodo sar\u00e0 quello dell\u2019ascolto alternativo dei cittadini (a\u00a0partire dai bambini) promotori di obiettivi di pubblico interesse e la\u00a0concertazione con tutti gli attori pubblici e privati che agiscono sul\u00a0territorio.<br \/>\nIl cuore di questo percorso sar\u00e0 in un Ufficio di Piano che raccolga\u00a0gli input e coordini il lavoro che non sar\u00e0 certamente limitato al\u00a0livello locale ma si aprir\u00e0 a contributi, idee e apporti\u00a0internazionali, come \u00e8 giusto che sia per una citt\u00e0 che vuole tornare\u00a0ad essere internazionale.<\/p>\n<p>I parametri che permetteranno di misurare lo sviluppo della nuova\u00a0citt\u00e0 saranno il tempo, con riferimento a quello necessario per gli\u00a0spostamenti fra i diversi nodi della citt\u00e0 e lo spazio, inteso come\u00a0metri quadri destinati all\u2019uso sociale e collettivo ed alle aree\u00a0pedonali, come ettari destinati al verde, come chilometri destinati\u00a0alle piste ciclabili, la cui rete dovr\u00e0 collegare innanzitutto scuole<br \/>\ned uffici intesi come luoghi vivi espressione dei bisogni della citt\u00e0.\u00a0Le scuole avranno un ruolo centrale, attraverso una razionalizzazione\u00a0ed una riqualificazione del patrimonio scolastico che dovr\u00e0 costituire\u00a0l\u2019asse portante di nuovi centri di aggregazione rivolti all\u2019intera<br \/>\ncomunit\u00e0.<br \/>\nIl tutto avverr\u00e0 unendo la visione rivolta all\u2019area metropolitana da\u00a0un lato e ai quartieri dall\u2019altro, coniugando una pianificazione su\u00a0larga scala rivolta soprattutto alle necessit\u00e0 infrastrutturali e alle\u00a0grandi reti e la pianificazione di interventi mirati nei territori,\u00a0rivolti alla riqualificazione degli spazi, alla vivibilit\u00e0 e alla\u00a0fruibilit\u00e0 della citt\u00e0.<br \/>\nIl nuovo PRG dovr\u00e0 assicurare la realizzazione di un nuovo assetto\u00a0della rete del trasporto pubblico, al fine di promuovere\u00a0l\u2019intermodalit\u00e0, attraverso un\u2019attenta valutazione degli aspetti\u00a0pianificatori, tecnologici ed economici che consenta di selezionare le\u00a0opere da prevedere nel Piano, e della viabilit\u00e0 di area vasta e di\u00a0rango sovracomunale come del sistema delle \u201cporte\u201d e degli accessi e\u00a0delle \u201creti lunghe\u201d (funzioni e rango del Porto e relazioni\u00a0citt\u00e0-aeroporto).<\/p>\n<p>Il nuovo PRG dovr\u00e0 rispondere alla domanda di residenza che \u00e8\u00a0radicalmente mutata negli ultimi anni: servono case pi\u00f9 piccole ed\u00a0economiche di quelle che oggi sono disponibili nel mercato\u00a0immobiliare, innovando il patrimonio esistente in termini energetici e\u00a0di qualit\u00e0 architettonica. Nessuna nuova aggressione al territorio\u00a0urbano o nuova espansione del tessuto urbano ma si proceder\u00e0,\u00a0pertanto, ad una grande operazione di manutenzione e\/o riuso e\u00a0rifunzionalizzazione del patrimonio edilizio e, segnatamente, di\u00a0quello abitativo.<br \/>\nGrazie al nuovo PRG, inoltre, si apriranno nuovi spazi per la citt\u00e0 di\u00a0Palermo che diventer\u00e0 una citt\u00e0 policentrica a partire dai vuoti\u00a0urbani attuali, quelle grandi aree oggi in stato di abbandono o\u00a0sottoutilizzate rispetto alle loro potenzialit\u00e0: l\u2019area Lolli \u00a0\/\u00a0Notarbartolo, della Fiera, ex Ospedale Psichiatrico, il piano\u00a0dell\u2019Ucciardone, il Mercato Orto-frutticolo, tutte micro centralit\u00e0\u00a0sparse nel territorio capaci di attivare processi di orgoglio da parte\u00a0della cittadinanza.<br \/>\nVa attribuito un nuovo significato funzionale e simbolico &#8211; che\u00a0contrasti e superi la percezione negativa generata dalle attuali\u00a0condizioni di discontinuit\u00e0 e marginalit\u00e0 urbana &#8211; al viale Regione\u00a0Siciliana ed al fiume Oreto, da trasformare da elementi di\u00a0discontinuit\u00e0 e frammentazione urbana in nuovi elementi di\u00a0rifondazione del sistema urbano.<br \/>\nLa Costa Sud e la linea del mare devono diventare quello che il Centro\u00a0Storico \u00e8 stato per la citt\u00e0 degli anni 90, una nuova fonte di\u00a0vitalit\u00e0 e una valorizzazione che attivi un processo di rinascita in\u00a0tutte le aree di quelli che sono stati i porti storici (Sferracavallo,\u00a0Mondello, Vergine Maria, Arenella, Acquasanta, Cala, Sant\u2019Erasmo,\u00a0Bandita)<br \/>\nLa rete dei parchi (da Montepellegrino alla Favorita, al parco\u00a0dell\u2019Oreto ed oltre) e quella dei giardini storici saranno il nuovo\u00a0Teatro Massimo, non solo in termini simbolici ma anche in termini di<br \/>\nricaduta effettiva e di rete sul territorio.<br \/>\nSar\u00e0 anche necessaria una razionalizzazione delle aree industriali,\u00a0creando una piattaforma logistica urbana e, allo stesso tempo\u00a0rafforzando e consolidando le funzioni commerciali di altre aree oggi\u00a0non pi\u00f9 votate a finalit\u00e0 produttive.<br \/>\nIl PRG dovr\u00e0 assecondare e rafforzare i processi di trasformazione in\u00a0citt\u00e0 digitale attraverso il modello della Smart City, a partire dalla\u00a0riallocazione delle strutture direzionali e dalla creazione di<br \/>\nprocessi di Smart Health, tesi da un lato alla razionalizzazione delle\u00a0strutture esistenti e dall\u2019altro lato alle nuove localizzazioni nei\u00a0tessuti urbani che maggiormente ne appaiono sprovvisti.<br \/>\nPer la Cultura tramite si dovr\u00e0 prevedere l\u2019istituzione del distretto\u00a0culturale, teatrale, musicale e la realizzazione del Museo Diffuso\u00a0delle risorse culturali, di un Nuovo Polo Congressuale, di un Nuovo<br \/>\nCentro Religioso interculturale, del Museo della Citt\u00e0 o del Racconto\u00a0urbano, della Casa delle Culture, della Scuola internazionale della\u00a0Cultura , della Casa delle differenze, Nuovo museo all\u2019Ucciardone, il<br \/>\n\u201cLaboratorio\u201d della Legalit\u00e0, il \u201cLaboratorio\u201d delle Pari Opportunit\u00e0,\u00a0il \u201cLaboratorio\u201d permanente di Progettazione Partecipata della Citt\u00e0.<br \/>\nDovranno essere introdotti anche nuovi strumenti per la \u201cmessa a\u00a0reddito\u201d della citt\u00e0 attraverso un processo di internazionalizzazione,\u00a0da un lato, e l\u2019attivazione di strumenti (come gli usi civici, gli<br \/>\noneri e i diritti edificatori, le misure perequative, etc) \u00a0che\u00a0consentano di conseguire una Economia urbana intelligente e\u00a0responsabile.<\/p>\n<p>Questi in sintesi i punti chiave dell\u2019idea che sottende alle linee guida<\/p>\n<p>&#8211; \u00a0 \u00a01 Supportare e rendere credibile la candidatura di Palermo a\u00a0Capitale Europea della Cultura nel 2019;<br \/>\n&#8211; \u00a0 \u00a02. Individuare nel fiume Oreto e nella Circonvallazione di viale\u00a0Regione Siciliana, nell\u2019oltre Oreto e nell\u2019oltre Circonvallazione i\u00a0nuovi poli di trasformazione della Citt\u00e0;<br \/>\n&#8211; \u00a0 \u00a03. Ambire ad una dimensione metropolitana in vista della nuova forma\u00a0amministrativa di Citt\u00e0 metropolitana, seguendo una logica di\u00a0decentramento e di costruzione delle nuove Municipalit\u00e0 urbane e di\u00a0delocalizzazione dei servizi attrattori di un\u2019utenza extra-urbana;<br \/>\n&#8211; \u00a0 \u00a04. Trasformare la Citt\u00e0, sebbene sterilizzandone il costo per le\u00a0casse dell\u2019Amministrazione Comunale (dalla Lista dei sogni ad\u00a0un\u2019Agenda di programma);<br \/>\n&#8211; \u00a0 \u00a05. Costruire la nuova Citt\u00e0 \u00a0attraverso un processo di ascolto\u00a0alternativo di cittadini (bambini ed adulti), promotori di obiettivi\u00a0di pubblico interesse e la concertazione con gli Enti pubblici e\u00a0morali.<br \/>\n&#8211; \u00a0 \u00a06. Far riacquisire centralit\u00e0 e vivibilit\u00e0 alla Citt\u00e0 inespressa\u00a0della costa Sud, il nuovo \u201cCentro Storico\u201d degli anni \u201990;<br \/>\n&#8211; \u00a0 \u00a07. Favorire lo sviluppo verticale della Citt\u00e0 al fine di limitare il\u00a0consumo del suolo e valorizzare il paesaggio urbano in quei contesti\u00a0connotati da disordine urbanistico;<br \/>\n&#8211; \u00a0 \u00a08. Nuovo orientamento degli impianti e del patrimonio scolastico in\u00a0centri di aggregazione per le famiglie;<br \/>\n&#8211; \u00a0 \u00a09. Assecondare e rafforzare i processi di trasformazione in Citt\u00e0\u00a0digitale attraverso il modello della Smart City, a partire dalla\u00a0riallocazione delle strutture direzionali e dall\u2019attivazione di\u00a0processi di Smart Health, \u00a0tesi da un lato alla razionalizzazione\u00a0delle strutture esistenti e dall\u2019altro lato alle nuove localizzazioni\u00a0nei tessuti urbani che maggiormente ne appaiono sprovvisti, in chiave\u00a0ovviamente metropolitana.<br \/>\n&#8211; \u00a0 \u00a010. Assicurare la realizzazione di un nuovo assetto della rete del\u00a0trasporto pubblico, al fine di promuovere l\u2019intermodalit\u00e0, attraverso\u00a0un\u2019attenta valutazione degli aspetti pianificatori, tecnologici ed\u00a0economici che consenta di selezionare le opere da prevedere nel\u00a0redigendo Piano;<br \/>\n&#8211; \u00a0 \u00a011. Rispondere alla domanda di residenza che si \u00e8 radicalmente\u00a0trasformata: servono case pi\u00f9 piccole ed economiche di quelle oggi\u00a0disponibili sul mercato immobiliare;<br \/>\n&#8211; \u00a0 \u00a012. Aumentare la qualit\u00e0 e la quantit\u00e0 degli spazi pubblici<br \/>\n&#8211; \u00a0 \u00a013. Innovare il patrimonio edilizio esistente in termini energetici\u00a0e \u201cdi qualit\u00e0 architettonica\u201d,<br \/>\n&#8211; \u00a0 \u00a014. Convertire le distanze spaziali, espresse in metri, in distanze\u00a0temporali, implementando la rete dei servizi e riordinando le funzioni\u00a0(scuole, attrezzature, attivit\u00e0 del terziario, etc.)<br \/>\n&#8211; \u00a0 \u00a015. Confermare il ruolo di Citt\u00e0 snodo del Mediterraneo,\u00a0interculturale e dell\u2019integrazione;<br \/>\n&#8211; \u00a0 \u00a016. Dovr\u00e0 essere individuata una area specifica da destinare ad una\u00a0Piattaforma Logistica Urbana, consolidando le funzioni commerciali e\u00a0non pi\u00f9 produttive di alcune aree prima a differente vocazione e\u00a0riattivare le aree produttive ed industriali frammentate che potranno\u00a0rigenerarsi in chiave residenziale;<br \/>\n&#8211; \u00a0 \u00a017. Mettere a reddito la Citt\u00e0, attraverso un processo di\u00a0internazionalizzazione da un lato e l\u2019attivazione di strumenti ed\u00a0istituti giuridici (usi civici, oneri e diritti edificatori, misure\u00a0perequative, etc.) dall\u2019altro lato che consentano di conseguire\u00a0un\u2019Economia urbana intelligente e responsabile;<br \/>\n&#8211; \u00a0 \u00a018. Creare un policentrismo a partire dai vuoti urbani, ovvero una\u00a0punteggiata di micro-centralit\u00e0 sparse nel territorio comunale che\u00a0cerchi di attivare processi di orgoglio da parte della cittadinanza\u00a0nei confronti del proprio pezzo di citt\u00e0. Ci\u00f2 potr\u00e0 ridurre anche la\u00a0pressione centripeta in termini di funzioni e di mobilit\u00e0.<br \/>\nLe Nuove polarit\u00e0 saranno l\u2019area Lolli \u00a0\/ Notarbartolo, della Fiera,\u00a0ex Ospedale Psichiatrico, il piano dell\u2019Ucciardone, il Mercato\u00a0Orto-frutticolo,<\/p>\n<p>Le Direttive contengono in gran parte indicazioni che si riferiscono\u00a0non solo all\u2019immagine della nuova Citt\u00e0 \u00a0ma anche agli approfondimenti\u00a0(demografici, geologici, economici, sociali, etc.) necessari alla\u00a0costruzione del nuovo strumento<\/p>\n<div id=\"voism-1499827026\" class=\"voism-fine voism-entity-placement\"><a href=\"https:\/\/amzn.to\/2Y0db7E\" aria-label=\"\"><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>PALERMO: Sono state presentate oggi, nel corso di una conferenza stampa a Villa\u00a0Niscemi, le linee guida elaborate dalla Giunta Comunale per la\u00a0redazione del nuovo Piano Regolatore. Di seguito una sintesi della presentazione. Il nuovo Piano Regolatore Generale di Palermo sar\u00e0 lo strumento per\u00a0trasformare la citt\u00e0 rendendola contemporanea, moderna e sostenibile.\u00a0Miriamo a modellare lo sviluppo della &#8230;<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2454],"tags":[],"class_list":["post-1475","post","type-post","status-publish","format-standard","hentry","category-news"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"PALERMO: Sono state presentate oggi, nel corso di una conferenza stampa a Villa Niscemi, le linee guida elaborate dalla Giunta Comunale per la redazione del nuovo Piano Regolatore. Di seguito una sintesi della presentazione. Il nuovo Piano Regolatore Generale di Palermo sar\u00e0 lo strumento per trasformare la citt\u00e0 rendendola contemporanea, moderna e sostenibile. Miriamo a modellare lo sviluppo della\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Redazione\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"VOIS MAGAZINE | Notizie | Curiosit\u00e0 | Eventi | Gossip |Imprese\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Verso Palermo 2050, le nuove linee guida del PRG | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |\" \/>\n\t\t<meta property=\"og:description\" content=\"PALERMO: Sono state presentate oggi, nel corso di una conferenza stampa a Villa Niscemi, le linee guida elaborate dalla Giunta Comunale per la redazione del nuovo Piano Regolatore. Di seguito una sintesi della presentazione. Il nuovo Piano Regolatore Generale di Palermo sar\u00e0 lo strumento per trasformare la citt\u00e0 rendendola contemporanea, moderna e sostenibile. Miriamo a modellare lo sviluppo della\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-10-25T10:40:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-11-18T14:56:47+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Verso Palermo 2050, le nuove linee guida del PRG | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |\" \/>\n\t\t<meta name=\"twitter:description\" content=\"PALERMO: Sono state presentate oggi, nel corso di una conferenza stampa a Villa Niscemi, le linee guida elaborate dalla Giunta Comunale per la redazione del nuovo Piano Regolatore. Di seguito una sintesi della presentazione. Il nuovo Piano Regolatore Generale di Palermo sar\u00e0 lo strumento per trasformare la citt\u00e0 rendendola contemporanea, moderna e sostenibile. Miriamo a modellare lo sviluppo della\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2012\\\/10\\\/25\\\/verso-palermo-2050-le-nuove-linee-guida-del-prg\\\/#article\",\"name\":\"Verso Palermo 2050, le nuove linee guida del PRG | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\\u00c3 | Eventi | Politica |\",\"headline\":\"Verso Palermo 2050, le nuove linee guida del PRG\",\"author\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/author\\\/redazione-vois\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.voismagazine.it\\\/dp\\\/wp-content\\\/uploads\\\/2012\\\/10\\\/image71-e1351161583775.jpg\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2012\\\/10\\\/25\\\/verso-palermo-2050-le-nuove-linee-guida-del-prg\\\/#articleImage\"},\"datePublished\":\"2012-10-25T12:40:39+02:00\",\"dateModified\":\"2012-11-18T15:56:47+01:00\",\"inLanguage\":\"it-IT\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2012\\\/10\\\/25\\\/verso-palermo-2050-le-nuove-linee-guida-del-prg\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2012\\\/10\\\/25\\\/verso-palermo-2050-le-nuove-linee-guida-del-prg\\\/#webpage\"},\"articleSection\":\"News\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2012\\\/10\\\/25\\\/verso-palermo-2050-le-nuove-linee-guida-del-prg\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/#listItem\",\"name\":\"Informazione\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/#listItem\",\"position\":2,\"name\":\"Informazione\",\"item\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/news\\\/#listItem\",\"name\":\"News\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/news\\\/#listItem\",\"position\":3,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2012\\\/10\\\/25\\\/verso-palermo-2050-le-nuove-linee-guida-del-prg\\\/#listItem\",\"name\":\"Verso Palermo 2050, le nuove linee guida del PRG\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/#listItem\",\"name\":\"Informazione\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2012\\\/10\\\/25\\\/verso-palermo-2050-le-nuove-linee-guida-del-prg\\\/#listItem\",\"position\":4,\"name\":\"Verso Palermo 2050, le nuove linee guida del PRG\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/category\\\/informazione\\\/news\\\/#listItem\",\"name\":\"News\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/#organization\",\"name\":\"VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\\u00c3  | Eventi | Politica |\",\"url\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/author\\\/redazione-vois\\\/#author\",\"url\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/author\\\/redazione-vois\\\/\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2012\\\/10\\\/25\\\/verso-palermo-2050-le-nuove-linee-guida-del-prg\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddf295f5b0124aa54ab77deb890c3069285db17b90e13d8a3a3e98f7b9344c09?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Redazione\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2012\\\/10\\\/25\\\/verso-palermo-2050-le-nuove-linee-guida-del-prg\\\/#webpage\",\"url\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2012\\\/10\\\/25\\\/verso-palermo-2050-le-nuove-linee-guida-del-prg\\\/\",\"name\":\"Verso Palermo 2050, le nuove linee guida del PRG | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\\u00c3 | Eventi | Politica |\",\"description\":\"PALERMO: Sono state presentate oggi, nel corso di una conferenza stampa a Villa Niscemi, le linee guida elaborate dalla Giunta Comunale per la redazione del nuovo Piano Regolatore. Di seguito una sintesi della presentazione. Il nuovo Piano Regolatore Generale di Palermo sar\\u00e0 lo strumento per trasformare la citt\\u00e0 rendendola contemporanea, moderna e sostenibile. Miriamo a modellare lo sviluppo della\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/2012\\\/10\\\/25\\\/verso-palermo-2050-le-nuove-linee-guida-del-prg\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/author\\\/redazione-vois\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/author\\\/redazione-vois\\\/#author\"},\"datePublished\":\"2012-10-25T12:40:39+02:00\",\"dateModified\":\"2012-11-18T15:56:47+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/#website\",\"url\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/\",\"name\":\"VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\\u00c3  | Eventi | Politica |\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.voismagazine.it\\\/dp\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Verso Palermo 2050, le nuove linee guida del PRG | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |","description":"PALERMO: Sono state presentate oggi, nel corso di una conferenza stampa a Villa Niscemi, le linee guida elaborate dalla Giunta Comunale per la redazione del nuovo Piano Regolatore. Di seguito una sintesi della presentazione. Il nuovo Piano Regolatore Generale di Palermo sar\u00e0 lo strumento per trasformare la citt\u00e0 rendendola contemporanea, moderna e sostenibile. Miriamo a modellare lo sviluppo della","canonical_url":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/#article","name":"Verso Palermo 2050, le nuove linee guida del PRG | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |","headline":"Verso Palermo 2050, le nuove linee guida del PRG","author":{"@id":"https:\/\/www.voismagazine.it\/dp\/author\/redazione-vois\/#author"},"publisher":{"@id":"https:\/\/www.voismagazine.it\/dp\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.voismagazine.it\/dp\/wp-content\/uploads\/2012\/10\/image71-e1351161583775.jpg","@id":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/#articleImage"},"datePublished":"2012-10-25T12:40:39+02:00","dateModified":"2012-11-18T15:56:47+01:00","inLanguage":"it-IT","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/#webpage"},"isPartOf":{"@id":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/#webpage"},"articleSection":"News"},{"@type":"BreadcrumbList","@id":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp#listItem","position":1,"name":"Home","item":"https:\/\/www.voismagazine.it\/dp","nextItem":{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/#listItem","name":"Informazione"}},{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/#listItem","position":2,"name":"Informazione","item":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/news\/#listItem","name":"News"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/news\/#listItem","position":3,"name":"News","item":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/#listItem","name":"Verso Palermo 2050, le nuove linee guida del PRG"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/#listItem","name":"Informazione"}},{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/#listItem","position":4,"name":"Verso Palermo 2050, le nuove linee guida del PRG","previousItem":{"@type":"ListItem","@id":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/news\/#listItem","name":"News"}}]},{"@type":"Organization","@id":"https:\/\/www.voismagazine.it\/dp\/#organization","name":"VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3  | Eventi | Politica |","url":"https:\/\/www.voismagazine.it\/dp\/"},{"@type":"Person","@id":"https:\/\/www.voismagazine.it\/dp\/author\/redazione-vois\/#author","url":"https:\/\/www.voismagazine.it\/dp\/author\/redazione-vois\/","name":"Redazione","image":{"@type":"ImageObject","@id":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/ddf295f5b0124aa54ab77deb890c3069285db17b90e13d8a3a3e98f7b9344c09?s=96&d=mm&r=g","width":96,"height":96,"caption":"Redazione"}},{"@type":"WebPage","@id":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/#webpage","url":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/","name":"Verso Palermo 2050, le nuove linee guida del PRG | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |","description":"PALERMO: Sono state presentate oggi, nel corso di una conferenza stampa a Villa Niscemi, le linee guida elaborate dalla Giunta Comunale per la redazione del nuovo Piano Regolatore. Di seguito una sintesi della presentazione. Il nuovo Piano Regolatore Generale di Palermo sar\u00e0 lo strumento per trasformare la citt\u00e0 rendendola contemporanea, moderna e sostenibile. Miriamo a modellare lo sviluppo della","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.voismagazine.it\/dp\/#website"},"breadcrumb":{"@id":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/#breadcrumblist"},"author":{"@id":"https:\/\/www.voismagazine.it\/dp\/author\/redazione-vois\/#author"},"creator":{"@id":"https:\/\/www.voismagazine.it\/dp\/author\/redazione-vois\/#author"},"datePublished":"2012-10-25T12:40:39+02:00","dateModified":"2012-11-18T15:56:47+01:00"},{"@type":"WebSite","@id":"https:\/\/www.voismagazine.it\/dp\/#website","url":"https:\/\/www.voismagazine.it\/dp\/","name":"VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3  | Eventi | Politica |","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.voismagazine.it\/dp\/#organization"}}]},"og:locale":"it_IT","og:site_name":"VOIS MAGAZINE | Notizie | Curiosit\u00e0 | Eventi | Gossip |Imprese","og:type":"article","og:title":"Verso Palermo 2050, le nuove linee guida del PRG | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |","og:description":"PALERMO: Sono state presentate oggi, nel corso di una conferenza stampa a Villa Niscemi, le linee guida elaborate dalla Giunta Comunale per la redazione del nuovo Piano Regolatore. Di seguito una sintesi della presentazione. Il nuovo Piano Regolatore Generale di Palermo sar\u00e0 lo strumento per trasformare la citt\u00e0 rendendola contemporanea, moderna e sostenibile. Miriamo a modellare lo sviluppo della","og:url":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/","article:published_time":"2012-10-25T10:40:39+00:00","article:modified_time":"2012-11-18T14:56:47+00:00","twitter:card":"summary","twitter:title":"Verso Palermo 2050, le nuove linee guida del PRG | VOIS MAGAZINE | Informazione | Cultura | Mondo Imprese | Curiosit\u00c3 | Eventi | Politica |","twitter:description":"PALERMO: Sono state presentate oggi, nel corso di una conferenza stampa a Villa Niscemi, le linee guida elaborate dalla Giunta Comunale per la redazione del nuovo Piano Regolatore. Di seguito una sintesi della presentazione. Il nuovo Piano Regolatore Generale di Palermo sar\u00e0 lo strumento per trasformare la citt\u00e0 rendendola contemporanea, moderna e sostenibile. Miriamo a modellare lo sviluppo della"},"aioseo_meta_data":{"post_id":"1475","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-12-29 02:49:05","updated":"2025-12-29 02:49:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.voismagazine.it\/dp\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/\" title=\"Informazione\">Informazione<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/news\/\" title=\"News\">News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVerso Palermo 2050, le nuove linee guida del PRG\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.voismagazine.it\/dp"},{"label":"Informazione","link":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/"},{"label":"News","link":"https:\/\/www.voismagazine.it\/dp\/category\/informazione\/news\/"},{"label":"Verso Palermo 2050, le nuove linee guida del PRG","link":"https:\/\/www.voismagazine.it\/dp\/2012\/10\/25\/verso-palermo-2050-le-nuove-linee-guida-del-prg\/"}],"_links":{"self":[{"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/posts\/1475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/comments?post=1475"}],"version-history":[{"count":0,"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/posts\/1475\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/media?parent=1475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/categories?post=1475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.voismagazine.it\/dp\/wp-json\/wp\/v2\/tags?post=1475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}